

{"id":163,"count":2,"description":"<p>In Canelli, einer Gemeinde zwischen Langhe und Monferrato, finden sich zwei einzigartige und charakterstarke Rebsorten: der Wei\u00dfe Muskateller aus Canelli und der Brachetto. Der stark kalkhaltige Boden tr\u00e4gt zusammen mit dem gem\u00e4\u00dfigten Klima zur Produktion reichhaltiger Weine, wie Asti DOCG, Brachetto und Moscato d'Asti Fratelli Aliberti, bei. Diese drei Weine passen perfekt zu trockenem Geb\u00e4ck, Kuchen, Schokoladendesserts, frischem Obst, Waldbeeren, Backwaren, Obstsalat und Obsttorten.<\/p>","link":"https:\/\/www.arione.it\/de\/collection\/f-lli-aliberti-de\/","name":"F.lli Aliberti","slug":"f-lli-aliberti-de","taxonomy":"collection","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.arione.it\/de\/wp-json\/wp\/v2\/collection\/163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arione.it\/de\/wp-json\/wp\/v2\/collection"}],"about":[{"href":"https:\/\/www.arione.it\/de\/wp-json\/wp\/v2\/taxonomies\/collection"}]}}